{"id":140,"count":1,"description":"","link":"https:\/\/fotka.com\/blog\/tag\/co-na-prezent\/","name":"co na prezent","slug":"co-na-prezent","taxonomy":"post_tag","meta":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.2 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>co na prezent | Fotka<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/fotka.com\/blog\/tag\/co-na-prezent\/\" \/>\n<meta property=\"og:locale\" content=\"pl_PL\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"co na prezent | Fotka\" \/>\n<meta property=\"og:url\" content=\"https:\/\/fotka.com\/blog\/tag\/co-na-prezent\/\" \/>\n<meta property=\"og:site_name\" content=\"Fotka\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"CollectionPage\",\"@id\":\"https:\/\/fotka.com\/blog\/tag\/co-na-prezent\/\",\"url\":\"https:\/\/fotka.com\/blog\/tag\/co-na-prezent\/\",\"name\":\"co na prezent | Fotka\",\"isPartOf\":{\"@id\":\"https:\/\/fotka.com\/blog\/#website\"},\"breadcrumb\":{\"@id\":\"https:\/\/fotka.com\/blog\/tag\/co-na-prezent\/#breadcrumb\"},\"inLanguage\":\"pl-PL\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/fotka.com\/blog\/tag\/co-na-prezent\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Strona g\u0142\u00f3wna\",\"item\":\"https:\/\/fotka.com\/blog\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"co na prezent\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/fotka.com\/blog\/#website\",\"url\":\"https:\/\/fotka.com\/blog\/\",\"name\":\"Fotka\",\"description\":\"Blog pe\u0142en porad o randkach, zwi\u0105zkach i relacjach\",\"publisher\":{\"@id\":\"https:\/\/fotka.com\/blog\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/fotka.com\/blog\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"pl-PL\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/fotka.com\/blog\/#organization\",\"name\":\"Fotka\",\"url\":\"https:\/\/fotka.com\/blog\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pl-PL\",\"@id\":\"https:\/\/fotka.com\/blog\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/fotka.com\/blog\/wp-content\/uploads\/2019\/11\/logo.png\",\"contentUrl\":\"https:\/\/fotka.com\/blog\/wp-content\/uploads\/2019\/11\/logo.png\",\"width\":124,\"height\":37,\"caption\":\"Fotka\"},\"image\":{\"@id\":\"https:\/\/fotka.com\/blog\/#\/schema\/logo\/image\/\"},\"sameAs\":[\"https:\/\/www.facebook.com\/fotkapl\/\",\"https:\/\/www.instagram.com\/fotka_com\/\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"co na prezent | Fotka","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/fotka.com\/blog\/tag\/co-na-prezent\/","og_locale":"pl_PL","og_type":"article","og_title":"co na prezent | Fotka","og_url":"https:\/\/fotka.com\/blog\/tag\/co-na-prezent\/","og_site_name":"Fotka","twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"CollectionPage","@id":"https:\/\/fotka.com\/blog\/tag\/co-na-prezent\/","url":"https:\/\/fotka.com\/blog\/tag\/co-na-prezent\/","name":"co na prezent | Fotka","isPartOf":{"@id":"https:\/\/fotka.com\/blog\/#website"},"breadcrumb":{"@id":"https:\/\/fotka.com\/blog\/tag\/co-na-prezent\/#breadcrumb"},"inLanguage":"pl-PL"},{"@type":"BreadcrumbList","@id":"https:\/\/fotka.com\/blog\/tag\/co-na-prezent\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Strona g\u0142\u00f3wna","item":"https:\/\/fotka.com\/blog\/"},{"@type":"ListItem","position":2,"name":"co na prezent"}]},{"@type":"WebSite","@id":"https:\/\/fotka.com\/blog\/#website","url":"https:\/\/fotka.com\/blog\/","name":"Fotka","description":"Blog pe\u0142en porad o randkach, zwi\u0105zkach i relacjach","publisher":{"@id":"https:\/\/fotka.com\/blog\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/fotka.com\/blog\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"pl-PL"},{"@type":"Organization","@id":"https:\/\/fotka.com\/blog\/#organization","name":"Fotka","url":"https:\/\/fotka.com\/blog\/","logo":{"@type":"ImageObject","inLanguage":"pl-PL","@id":"https:\/\/fotka.com\/blog\/#\/schema\/logo\/image\/","url":"https:\/\/fotka.com\/blog\/wp-content\/uploads\/2019\/11\/logo.png","contentUrl":"https:\/\/fotka.com\/blog\/wp-content\/uploads\/2019\/11\/logo.png","width":124,"height":37,"caption":"Fotka"},"image":{"@id":"https:\/\/fotka.com\/blog\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/fotkapl\/","https:\/\/www.instagram.com\/fotka_com\/"]}]}},"_links":{"self":[{"href":"https:\/\/fotka.com\/blog\/wp-json\/wp\/v2\/tags\/140","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/fotka.com\/blog\/wp-json\/wp\/v2\/tags"}],"about":[{"href":"https:\/\/fotka.com\/blog\/wp-json\/wp\/v2\/taxonomies\/post_tag"}],"wp:post_type":[{"href":"https:\/\/fotka.com\/blog\/wp-json\/wp\/v2\/posts?tags=140"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}